{"id":5608,"date":"2026-04-16T09:59:03","date_gmt":"2026-04-16T07:59:03","guid":{"rendered":"https:\/\/careers.gruppopirola.com\/application\/tax-trainee-bologna\/"},"modified":"2026-04-16T09:59:03","modified_gmt":"2026-04-16T07:59:03","slug":"tax-trainee-bologna","status":"publish","type":"application","link":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/","title":{"rendered":"Tax &#8211; Trainee &#8211; Bologna"},"featured_media":0,"template":"","meta":{"_acf_changed":false},"categories":[],"class_list":["post-5608","application","type-application","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tax - Trainee - Bologna - Pirola Careers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tax - Trainee - Bologna - Pirola Careers\" \/>\n<meta property=\"og:description\" content=\"Pirola Pennuto Zei &#038; Associati, a leading professional firm in the field of tax and legal consultancy, is looking for undergraduate and recent graduates interested in undertaking a professional traineeship and professionals recently qualified for the Bologna office. \u00a0 The selected people, included in work teams, will be in charge of the following activities:\u00a0 \u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/\" \/>\n<meta property=\"og:site_name\" content=\"Pirola Careers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/en\\\/application\\\/tax-trainee-bologna\\\/\",\"url\":\"https:\\\/\\\/careers.gruppopirola.com\\\/en\\\/application\\\/tax-trainee-bologna\\\/\",\"name\":\"Tax - Trainee - Bologna - Pirola Careers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/#website\"},\"datePublished\":\"2026-04-16T07:59:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/en\\\/application\\\/tax-trainee-bologna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/careers.gruppopirola.com\\\/en\\\/application\\\/tax-trainee-bologna\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/en\\\/application\\\/tax-trainee-bologna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/careers.gruppopirola.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tax &#8211; Trainee &#8211; Bologna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/#website\",\"url\":\"https:\\\/\\\/careers.gruppopirola.com\\\/\",\"name\":\"Careers | Gruppo Pirola\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/careers.gruppopirola.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/#organization\",\"name\":\"Gruppo Pirola\",\"url\":\"https:\\\/\\\/careers.gruppopirola.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/careers.gruppopirola.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ppza-logo.svg\",\"contentUrl\":\"https:\\\/\\\/careers.gruppopirola.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ppza-logo.svg\",\"width\":164,\"height\":185,\"caption\":\"Gruppo Pirola\"},\"image\":{\"@id\":\"https:\\\/\\\/careers.gruppopirola.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tax - Trainee - Bologna - Pirola Careers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/","og_locale":"en_US","og_type":"article","og_title":"Tax - Trainee - Bologna - Pirola Careers","og_description":"Pirola Pennuto Zei &#038; Associati, a leading professional firm in the field of tax and legal consultancy, is looking for undergraduate and recent graduates interested in undertaking a professional traineeship and professionals recently qualified for the Bologna office. \u00a0 The selected people, included in work teams, will be in charge of the following activities:\u00a0 \u00a0 [&hellip;]","og_url":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/","og_site_name":"Pirola Careers","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/","url":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/","name":"Tax - Trainee - Bologna - Pirola Careers","isPartOf":{"@id":"https:\/\/careers.gruppopirola.com\/#website"},"datePublished":"2026-04-16T07:59:03+00:00","breadcrumb":{"@id":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/careers.gruppopirola.com\/en\/application\/tax-trainee-bologna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/careers.gruppopirola.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tax &#8211; Trainee &#8211; Bologna"}]},{"@type":"WebSite","@id":"https:\/\/careers.gruppopirola.com\/#website","url":"https:\/\/careers.gruppopirola.com\/","name":"Careers | Gruppo Pirola","description":"","publisher":{"@id":"https:\/\/careers.gruppopirola.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/careers.gruppopirola.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/careers.gruppopirola.com\/#organization","name":"Gruppo Pirola","url":"https:\/\/careers.gruppopirola.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/careers.gruppopirola.com\/#\/schema\/logo\/image\/","url":"https:\/\/careers.gruppopirola.com\/wp-content\/uploads\/2024\/06\/ppza-logo.svg","contentUrl":"https:\/\/careers.gruppopirola.com\/wp-content\/uploads\/2024\/06\/ppza-logo.svg","width":164,"height":185,"caption":"Gruppo Pirola"},"image":{"@id":"https:\/\/careers.gruppopirola.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/careers.gruppopirola.com\/en\/wp-json\/wp\/v2\/application\/5608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/careers.gruppopirola.com\/en\/wp-json\/wp\/v2\/application"}],"about":[{"href":"https:\/\/careers.gruppopirola.com\/en\/wp-json\/wp\/v2\/types\/application"}],"version-history":[{"count":0,"href":"https:\/\/careers.gruppopirola.com\/en\/wp-json\/wp\/v2\/application\/5608\/revisions"}],"wp:attachment":[{"href":"https:\/\/careers.gruppopirola.com\/en\/wp-json\/wp\/v2\/media?parent=5608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/careers.gruppopirola.com\/en\/wp-json\/wp\/v2\/categories?post=5608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}